{"id":5224,"date":"2019-05-31T15:01:05","date_gmt":"2019-05-31T15:01:05","guid":{"rendered":"https:\/\/www.revisamed.com.br\/blog\/?p=5224"},"modified":"2023-05-23T15:04:12","modified_gmt":"2023-05-23T18:04:12","slug":"dia-mundial-sem-tabaco","status":"publish","type":"post","link":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/","title":{"rendered":"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco"},"content":{"rendered":"\n<p>Comemorado em 31\/05, data \u00e9 destinada \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade. <\/p>\n\n\n\n<p>A Organiza\u00e7\u00e3o Mundial de Sa\u00fade <a href=\"https:\/\/www.paho.org\/pt\/topicos\/tabaco\">(OMS)<\/a> quer alertar sobre as doen\u00e7as e <strong>mortes evit\u00e1veis relacionadas ao tabagismo<\/strong>. De acordo com o Instituto Nacional do C\u00e2ncer&nbsp;<a href=\"https:\/\/www.inca.gov.br\/assuntos\/dia-mundial-sem-tabaco\">(INCA),<\/a> a ideia \u00e9 aumentar a conscientiza\u00e7\u00e3o do impacto negativo que o uso do cigarro e a exposi\u00e7\u00e3o ao fumo passivo exercem sobre a sa\u00fade pulmonar. <strong>Do c\u00e2ncer de pulm\u00e3o \u00e0s doen\u00e7as respirat\u00f3rios cr\u00f4nicos<\/strong> como asma e doen\u00e7a pulmonar obstrutiva cr\u00f4nica, incluindo bronquite e enfisema.<\/p>\n\n\n\n<p>Cerca de 90% dos c\u00e2nceres de pulm\u00e3o t\u00eam como causadores o tabaco fumado, em qualquer uma de suas formas. Voc\u00ea conhece os riscos do tabagismo para a sua sa\u00fade. Em resumo, o consumo do tabaco \u00e9 o principal  fator de risco para o desenvolvimento de c\u00e2ncer de pulm\u00e3o. \u00c9 tamb\u00e9m importante fator de risco para doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC), tuberculose, dentre outras enfermidades pulmonares. <\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-flat ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">A seguir, voc\u00ea vai saber:<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Dia_Mundial_Sem_Tabaco_fumante_passivo_tambem_corre_risco\" >Dia Mundial Sem Tabaco: fumante passivo tamb\u00e9m corre risco<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Doencas_pulmonares_o_que_sao\" >Doen\u00e7as pulmonares: o que s\u00e3o?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Cancer_de_pulmao\" >C\u00e2ncer de pulm\u00e3o<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Doenca_pulmonar_obstrutiva_cronica_DPOC\" >Doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC)<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Tuberculose\" >Tuberculose<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Como_parar_de_fumar\" >Como parar de fumar ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Rede_de_Tratamento_do_tabagismo_no_SUS\" >Rede de Tratamento do tabagismo no SUS<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Acoes_educativas_legislativas_e_economicas\" >A\u00e7\u00f5es educativas, legislativas e econ\u00f4micas<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Programa_de_Tratamento_do_tabagismo\" >Programa de Tratamento do tabagismo<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Por_que_as_pessoas_fumam\" >Por que as pessoas fumam?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Publicidade_e_tabagismo\" >Publicidade e tabagismo<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Quer_parar_de_fumar\" >Quer parar de fumar?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Procure_um_tratamento_especializado\" >Procure um tratamento especializado<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Abordagem\" >Abordagem<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Apoio_medicamentoso\" >Apoio medicamentoso<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Abstinencia\" >Abstin\u00eancia<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Recaida\" >Reca\u00edda<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Aumento_de_peso\" >Aumento de peso<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#Beneficios\" >Benef\u00edcios<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-dia-mundial-sem-tabaco-fumante-passivo-tambem-corre-risco\"><span class=\"ez-toc-section\" id=\"Dia_Mundial_Sem_Tabaco_fumante_passivo_tambem_corre_risco\"><\/span>Dia Mundial Sem Tabaco: fumante passivo tamb\u00e9m corre risco<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p> No Dia Mundial sem Tabaco, o Inca alerta que a exposi\u00e7\u00e3o ao <strong>tabagismo passivo<\/strong>. Ou seja, a exposi\u00e7\u00e3o involunt\u00e1ria \u00e0 fuma\u00e7a do cigarro, em curto per\u00edodo, pode acarretar rea\u00e7\u00f5es al\u00e9rgicas \u2014 rinite, tosse, conjuntivite, exacerba\u00e7\u00e3o de asma.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.revisamed.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1.jpg\" alt=\"Dia Mundial sem tabaco\" class=\"wp-image-6803\" width=\"343\" height=\"409\" srcset=\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1.jpg 800w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-600x717.jpg 600w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-251x300.jpg 251w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-768x918.jpg 768w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-700x837.jpg 700w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-410x490.jpg 410w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-100x120.jpg 100w, https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2020\/01\/Dia-Mundial-Sem-Tabaco-1-275x329.jpg 275w\" sizes=\"auto, (max-width: 343px) 100vw, 343px\" \/><\/figure><\/div>\n\n\n\n<p>A exposi\u00e7\u00e3o por longo tempo pode levar ao<strong> infarto agudo do mioc\u00e1rdio, c\u00e2ncer do pulm\u00e3o e doen\u00e7a pulmonar obstrutiva cr\u00f4nica &#8211; enfisema pulmonar e bronquite cr\u00f4nica).<\/strong> <\/p>\n\n\n\n<p>As crian\u00e7as tamb\u00e9m sofrem com pais fumantes. A <strong>exposi\u00e7\u00e3o passiva<\/strong> <strong>aumenta o n\u00famero de infec\u00e7\u00f5es respirat\u00f3rias<\/strong>.  O problema atinge tamb\u00e9m os<strong> beb\u00eas ainda no \u00fatero<\/strong>. As toxinas da fuma\u00e7a causam <strong>redu\u00e7\u00e3o do crescimento e da fun\u00e7\u00e3o pulmonar. <\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p> <br>O Dia Mundial Sem Tabaco \u2013 31 de maio \u2013 foi criado em 1987 pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) para alertar sobre as doen\u00e7as e mortes evit\u00e1veis relacionadas ao tabagismo. No Brasil, o INCA \u00e9 o respons\u00e1vel pela divulga\u00e7\u00e3o e elabora\u00e7\u00e3o do material t\u00e9cnico para subsidiar as comemora\u00e7\u00f5es em n\u00edveis federal, estadual e municipal. <\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-doencas-pulmonares-o-que-sao\"><span class=\"ez-toc-section\" id=\"Doencas_pulmonares_o_que_sao\"><\/span><strong>Doen\u00e7as pulmonares: o que s\u00e3o?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Doen\u00e7as pulmonares s\u00e3o aquelas que acometem os pulm\u00f5es, prejudicando o seu pleno funcionamento, como c\u00e2ncer de pulm\u00e3o, doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC), enfisema pulmonar e bronquite cr\u00f4nica. As enfermidades pulmonares podem causar incapacidade e morte prematura. <strong>Fumar \u00e9 fator de risco para doen\u00e7as respirat\u00f3rias. Parar de fumar ou nem iniciar \u00e9 a melhor forma de preven\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cancer-de-pulmao\"><span class=\"ez-toc-section\" id=\"Cancer_de_pulmao\"><\/span><strong>C\u00e2ncer de pulm\u00e3o<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O<strong> tabagismo \u00e9 a principal causa de c\u00e2ncer de pulm\u00e3o<\/strong>, respons\u00e1vel por <strong>mais de dois ter\u00e7os das mortes por esta doen\u00e7a no mund<\/strong>o. A exposi\u00e7\u00e3o ao fumo passivo, em casa ou no local de trabalho, tamb\u00e9m aumenta o risco de c\u00e2ncer de pulm\u00e3o. Este&nbsp;\u00e9 o segundo mais comum em homens e mulheres no Brasil (sem contar o c\u00e2ncer de pele n\u00e3o melanoma). E \u00e9 o primeiro em todo o mundo desde 1985, tanto em incid\u00eancia quanto em mortalidade.<\/p>\n\n\n\n<p>Em aproximadamente <strong>85% dos casos diagnosticados, o c\u00e2ncer de pulm\u00e3o est\u00e1 associado ao consumo de derivados de tabaco<\/strong>. Parar de fumar pode reduzir o risco de c\u00e2ncer de pulm\u00e3o: ap\u00f3s 10 anos, o risco cai para cerca de metade do de um n\u00e3o fumante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-doenca-pulmonar-obstrutiva-cronica-dpoc\"><span class=\"ez-toc-section\" id=\"Doenca_pulmonar_obstrutiva_cronica_DPOC\"><\/span><strong>Doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O <strong>tabagismo \u00e9 a principal causa de doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC<\/strong>), condi\u00e7\u00e3o que inclui a&nbsp;bronquite&nbsp;cr\u00f4nica e o enfisema pulmonar. O risco de desenvolver DPOC \u00e9 particularmente alto entre os indiv\u00edduos que come\u00e7am a fumar ainda jovens.  A fuma\u00e7a do tabaco diminui significativamente o desenvolvimento pulmonar.<\/p>\n\n\n\n<p>O <strong>consumo do tabaco tamb\u00e9m agrava a asma, <\/strong>o que restringe a atividade do indiv\u00edduo e contribui para a incapacidade. A cessa\u00e7\u00e3o precoce do tabagismo \u00e9 o tratamento mais eficaz para retardar a progress\u00e3o da DPOC e melhorar os sintomas da asma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tuberculose\"><span class=\"ez-toc-section\" id=\"Tuberculose\"><\/span><strong>Tuberculose<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A tuberculose \u00e9 uma doen\u00e7a infecciosa, grave e potencialmente mortal \u2014 se n\u00e3o for tratada. Ela \u00e9 transmitida pelo ar e pode atingir todos os \u00f3rg\u00e3os do corpo, especialmente os pulm\u00f5es. <strong>A tuberculose danifica os pulm\u00f5es e reduz a fun\u00e7\u00e3o pulmonar, situa\u00e7\u00e3o ainda mais exacerbada pelo tabagismo.<\/strong><\/p>\n\n\n\n<p>Os componentes qu\u00edmicos do tabaco podem desencadear infec\u00e7\u00f5es latentes da tuberculose. A tuberculose ativa \u2014 agravada pelos efeitos prejudiciais para a sa\u00fade dos pulm\u00f5es pelo uso do tabaco \u2014 aumenta substancialmente o <strong>risco de incapacidade e morte por insufici\u00eancia respirat\u00f3ria.  <\/strong>(Informa\u00e7\u00f5es extra\u00eddas do site do INCA.)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-parar-de-fumar\"><span class=\"ez-toc-section\" id=\"Como_parar_de_fumar\"><\/span>Como parar de fumar ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rede-de-tratamento-do-tabagismo-no-sus\"><span class=\"ez-toc-section\" id=\"Rede_de_Tratamento_do_tabagismo_no_SUS\"><\/span><strong>Rede de Tratamento do tabagismo no SUS<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>No Dia Mundial Sem Tabaco, \u00e9 importante que as pessoas saibam que o <a href=\"https:\/\/www.inca.gov.br\/programa-nacional-de-controle-do-tabagismo\/tratamento\">INCA<\/a> \u00e9 o \u00f3rg\u00e3o do Minist\u00e9rio da Sa\u00fade respons\u00e1vel pelo <a href=\"https:\/\/www.gov.br\/inca\/pt-br\/assuntos\/gestor-e-profissional-de-saude\/programa-nacional-de-controle-do-tabagismo\">Programa Nacional de Controle do Tabagismo (PNCT)<\/a>. \u00c9 tamb\u00e9m respons\u00e1vel pela articula\u00e7\u00e3o da Rede de Tratamento do Tabagismo no SUS, em parceria com Estados e Munic\u00edpios e Distrito Federal. <\/p>\n\n\n\n<p>A Rede foi organizada seguindo a l\u00f3gica de descentraliza\u00e7\u00e3o do SUS para que houvesse o gerenciamento regional. O Programa tem como premissa a intersetorialidade e a integralidade das a\u00e7\u00f5es. Cabe lembrar que desde 1989, <strong>o INCA desenvolve a\u00e7\u00f5es voltadas para o tratamento do tabagismo.<\/strong><\/p>\n\n\n\n<p>Atualmente, nos<strong> 26 estados da Federa\u00e7\u00e3o e no Distrito Federal, as secretarias estaduais de Sa\u00fade possuem coordena\u00e7\u00f5es do Programa de Controle do Tabagismo<\/strong>. Estas por sua vez, descentralizam as a\u00e7\u00f5es para seus respectivos munic\u00edpios, atuando de forma integrada.<\/p>\n\n\n\n<p>Assim, o tratamento de tabagismo no Brasil \u00e9 desenvolvido com base nas diretrizes do PNCT, que est\u00e1 sob a coordena\u00e7\u00e3o e gerenciamento da <strong>Divis\u00e3o de Controle do Tabagismo e Outros Fatores de Risco do INCA.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-acoes-educativas-legislativas-e-economicas\"><span class=\"ez-toc-section\" id=\"Acoes_educativas_legislativas_e_economicas\"><\/span>A\u00e7\u00f5es educativas, legislativas e econ\u00f4micas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>As a\u00e7\u00f5es educativas, legislativas e econ\u00f4micas desenvolvidas no Brasil v\u00eam gerando uma diminui\u00e7\u00e3o da aceita\u00e7\u00e3o social do tabagismo. Um n\u00famero cada vez maior de pessoas quer parar de fumar. Isto evidencia a import\u00e2ncia de <strong>priorizar o tratamento do fumante como uma estrat\u00e9gia fundamental no controle do tabagismo.<\/strong><\/p>\n\n\n\n<p>Desde 2002, o Minist\u00e9rio da Sa\u00fade vem publicando e atualizando portarias que incluem <strong>o tratamento do tabagismo na rede SUS, <\/strong> tanto na aten\u00e7\u00e3o b\u00e1sica quanto na m\u00e9dia e alta complexidade.  Definem formas de abordagem e tratamento do tabagismo.  Aprovam o plano para implanta\u00e7\u00e3o de protocolo cl\u00ednico e diretrizes terap\u00eauticas. <\/p>\n\n\n\n<p>Determinam a disponibiliza\u00e7\u00e3o pelo Minist\u00e9rio da Sa\u00fade aos munic\u00edpios com unidade de sa\u00fade que desenvolvem o tratamento do tabagistas. Isto incluindo desde os <strong>materiais de apoio aos medicamentos utilizados<\/strong> para esse fim. Al\u00e9m das formas de ades\u00e3o ao tratamento do tabagismo pelos munic\u00edpios e defini\u00e7\u00e3o do financiamento dos procedimentos a serem utilizados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-programa-de-tratamento-do-tabagismo\"><span class=\"ez-toc-section\" id=\"Programa_de_Tratamento_do_tabagismo\"><\/span>Programa de Tratamento do tabagismo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u00c9 importante destacar que ao ingressar no <strong>programa de tratamento do tabagismo<\/strong>, as gest\u00f5es de diversas inst\u00e2ncias assumem o compromisso de organiza\u00e7\u00e3o e implanta\u00e7\u00e3o das a\u00e7\u00f5es para o cuidado da pessoa tabagista. O tratamento inclui <strong>avalia\u00e7\u00e3o cl\u00ednica, abordagem m\u00ednima ou intensiva, individual ou em grupo e, se necess\u00e1rio, terapia medicamentosa juntamente com a abordagem intensiva.<\/strong><\/p>\n\n\n\n<p>\u00c9 importante salientar que as orienta\u00e7\u00f5es do PNCT est\u00e3o de acordo com as <strong>principais diretrizes internacionais relacionadas ao tratamento do tabagismo.<\/strong> Dessa forma, o SUS oferece ao fumante brasileiro que deseje parar de fumar um tratamento adequado, com metodologia embasada em evid\u00eancias cient\u00edficas. ( <em>fonte : texto extra\u00eddo do Programa Nacional do Controle do Tabagismo<\/em> )<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-por-que-as-pessoas-fumam\"><span class=\"ez-toc-section\" id=\"Por_que_as_pessoas_fumam\"><\/span><strong>Por que as pessoas fumam?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>A nicotina<\/strong>, presente em qualquer derivado do tabaco, \u00e9 considerada droga por possuir propriedades psicoativas.  Ou seja, ao ser inalada produz altera\u00e7\u00e3o no sistema nervoso central, <strong>trazendo modifica\u00e7\u00e3o no estado emocional e comportamental do usu\u00e1rio.<\/strong><\/p>\n\n\n\n<p><strong> <\/strong>O quadro de depend\u00eancia resulta em <strong>toler\u00e2ncia, abstin\u00eancia e comportamento compulsivo para consumir a droga,<\/strong> estabelecendo-se assim um padr\u00e3o de auto-administra\u00e7\u00e3o. Este padr\u00e3o \u00e9 caracterizado pela <strong>necessidade tanto f\u00edsica quanto psicol\u00f3gica da subst\u00e2ncia,<\/strong> apesar do conhecimento de seus efeitos prejudiciais \u00e0 sa\u00fade.<\/p>\n\n\n\n<p>Muitos s\u00e3o os fatores que podem levar a pessoa a experimentar drogas. \u00c9 hist\u00f3rica a tend\u00eancia humana de buscar formas de alterar sua consci\u00eancia de modo a produzir prazer e modificar seu humor. De maneira geral, <strong>a possibilidade do encontro com a droga se d\u00e1 na adolesc\u00eancia<\/strong>, fase caracterizada por muitas transforma\u00e7\u00f5es f\u00edsicas e emocionais , ang\u00fastias e busca de respostas.<\/p>\n\n\n\n<p>Dependendo da suscetibilidade individual, alguns fatores ser\u00e3o decisivos para <strong>estimular o indiv\u00edduo atender a essa tend\u00eancia humana de buscar nas drogas o al\u00edvio para suas tens\u00f5es<\/strong>. Entre elas, a <strong>aceita\u00e7\u00e3o social<\/strong> de uma determinada subst\u00e2ncia, seu f\u00e1cil acesso, uso da droga por pessoas que tenham papel de modelos de comportamento. Portanto, a sociedade pode contribuir de maneira significativa para que o acesso ao uso seja estimulado, causando adoecimentos em larga escala.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-publicidade-e-tabagismo\"><span class=\"ez-toc-section\" id=\"Publicidade_e_tabagismo\"><\/span>Publicidade e tabagismo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>No caso do <strong>tabagismo, vale destacar o papel que a publicidade exerceu<\/strong> e exerce na ado\u00e7\u00e3o do consumo de derivados do tabaco, especialmente cigarro. A publicidade veiculada pelas ind\u00fastrias aliou as demandas sociais e as fantasias dos diferentes grupos (adolescentes, jovens, mulheres, faixas economicamente mais pobres e com menor n\u00edvel de escolaridade) ao uso do cigarro.  <strong>A publicidade direta era feita por ve\u00edculos de comunica\u00e7\u00e3o de massa<\/strong>, por an\u00fancios atraentes e bem produzidos, o que <strong>est\u00e1 proibido no Brasil desde 1996.<\/strong> <\/p>\n\n\n\n<p>Os resultados das <strong>medidas de restri\u00e7\u00e3o \u00e0 publicidade no controle do tabagismo<\/strong> em v\u00e1rios pa\u00edses mostram que esse \u00e9 um instrumento leg\u00edtimo e necess\u00e1rio para a<strong> redu\u00e7\u00e3o do consumo. Isto associado \u00e0 medidas legislativas, econ\u00f4micas e educativas, entre outras.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quer-parar-de-fumar\"><span class=\"ez-toc-section\" id=\"Quer_parar_de_fumar\"><\/span><strong>Quer parar de fumar?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Equivocadamente muitas pessoas acreditam que o tabagista \u00e9 um<strong> \u201cviciado&#8221;, \u201csem for\u00e7a de vontade&#8221;, \u201cque n\u00e3o deixa de fumar porque n\u00e3o quer&#8221;<\/strong>. N\u00e3o \u00e9 isso. Na verdade <strong>quem fuma sofre de depend\u00eancia qu\u00edmica<\/strong>. Ou seja, \u00e9 algu\u00e9m que ao tentar deixar de fumar, se defronta com grandes desconfortos f\u00edsicos e psicol\u00f3gicos que trazem sofrimento, e que pode impor a necessidade de v\u00e1rias tentativas at\u00e9 que, finalmente consiga abandonar o tabaco. <\/p>\n\n\n\n<p>Entender o que acontece com o tabagista e suas tentativas de parar de fumar \u00e9 fundamental para que se possa ter a real dimens\u00e3o do problema. Portanto, se voc\u00ea quer<strong> parar de fumar comece escolhendo uma data para ser o seu primeiro dia sem cigarro. <\/strong>Este dia n\u00e3o precisa ser um dia de sofrimento. Fa\u00e7a dele uma ocasi\u00e3o especial e procure programar outra coisa que goste de fazer para se distrair e relaxar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-procure-um-tratamento-especializado\"><span class=\"ez-toc-section\" id=\"Procure_um_tratamento_especializado\"><\/span><strong>Procure um tratamento especializado<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se n\u00e3o consegue parar de fumar sozinho <strong>procure um tratamento especializado. <\/strong>Para informa\u00e7\u00f5es mais detalhadas voc\u00ea deve consultar a Coordena\u00e7\u00e3o de Controle do Tabagismo da sua Secretaria Estadual e\/ou Municipal de Sa\u00fade de sua vidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-abordagem\"><span class=\"ez-toc-section\" id=\"Abordagem\"><\/span><strong>Abordagem<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>Fumar \u00e9 um comportamento extremamente refor\u00e7ado diariamente.<\/strong> A abordagem tendo por base o modelo cognitivo comportamental \u00e9 a t\u00e9cnica recomendada para o tratamento do tabagista.<\/p>\n\n\n\n<p>Entre suas premissas est\u00e1 o entendimento de que o ato de fumar \u00e9 um comportamento aprendido, desencadeado e mantido por determinadas situa\u00e7\u00f5es e emo\u00e7\u00f5es, que leva a depend\u00eancia devido \u00e0s propriedades psicoativas da nicotina.<\/p>\n\n\n\n<p> O tratamento objetiva, portanto, a aprendizagem de um novo comportamento, atrav\u00e9s da promo\u00e7\u00e3o de mudan\u00e7as nas cren\u00e7as e desconstru\u00e7\u00e3o de vincula\u00e7\u00f5es comportamentais ao ato de fumar, combinando interven\u00e7\u00f5es cognitivas com treinamento de habilidades comportamentais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-apoio-medicamentoso\"><span class=\"ez-toc-section\" id=\"Apoio_medicamentoso\"><\/span><strong>Apoio medicamentoso<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O uso de medicamentos tem um papel bem definido no processo de cessa\u00e7\u00e3o do tabagismo. Ou seja, o de minimizar os sintomas da s\u00edndrome de abstin\u00eancia \u00e0 nicotina, facilitando a abordagem intensiva do tabagista&nbsp;. Medicamentos n\u00e3o devem ser utilizados isoladamente, e sim em associa\u00e7\u00e3o com uma boa abordagem. \u00c9 fundamental que o tabagista se sinta mais confiante para exercitar e por em pr\u00e1tica as orienta\u00e7\u00f5es recebidas durante as sess\u00f5es da abordagem intensiva.<\/p>\n\n\n\n<p><br>Os medicamentos disponibilizados pelo Minist\u00e9rio da Sa\u00fade para o tratamento do tabagismo na Rede do SUS s\u00e3o os seguintes: Terapia de Reposi\u00e7\u00e3o de Nicotina (adesivo transd\u00e9rmico e goma de mascar) e o Cloridrato de Bupropiona.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-abstinencia\"><span class=\"ez-toc-section\" id=\"Abstinencia\"><\/span><strong>Abstin\u00eancia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Considerada uma droga bastante danosa, a nicotina atua no sistema nervoso central como a coca\u00edna, hero\u00edna, \u00e1lcool, com uma diferen\u00e7a: leva entre 7 a 19 segundos para chegar ao c\u00e9rebro. \u00c9 normal, portanto, que, ao parar de fumar, os primeiros dias sem cigarros sejam os mais dif\u00edceis, por\u00e9m as dificuldades tendem a ser menores com o tempo.<\/p>\n\n\n\n<p>Quando o fumante para de fumar, pode apresentar alguns sintomas desagrad\u00e1veis, tais como: dor de cabe\u00e7a, tonteira, irritabilidade, agressividade, altera\u00e7\u00e3o do sono, dificuldade de concentra\u00e7\u00e3o, tosse, indisposi\u00e7\u00e3o g\u00e1strica e outros. Esses sintomas caracterizam a s\u00edndrome de abstin\u00eancia da nicotina, por\u00e9m, n\u00e3o acontecem com todos os fumantes que param de fumar. Quando acontecem, tendem a desaparecer em uma a duas semanas (alguns casos podem chegar a 4 semanas).<\/p>\n\n\n\n<p>Alguns dos sintomas, como dor de cabe\u00e7a, tonteira e tosse s\u00e3o sinais do restabelecimento do organismo. O sintoma mais intenso, e mais dif\u00edcil de se lidar, \u00e9 a chamada <strong>\u201cfissura&#8221; (grande vontade em fumar).<\/strong> \u00c9 importante saber que a <strong>\u201cfissura&#8221; geralmente n\u00e3o dura mais que 5 minutos, e<\/strong> tende a ficar mais tempo que os outros sintomas. Por\u00e9m, ela vai reduzindo gradativamente a sua intensidade e aumentando o intervalo entre um epis\u00f3dio e outro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-recaida\"><span class=\"ez-toc-section\" id=\"Recaida\"><\/span><strong>Reca\u00edda<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A reca\u00edda se caracteriza pelo retorno ao consumo de cigarros ap\u00f3s parar de fumar. <strong>Na condi\u00e7\u00e3o de tabagista, o paciente vai ao longo de sua vida estabelecendo associa\u00e7\u00f5es com seu cotidiano e o comportamento de fumar. <\/strong>Ao deixar de fumar e realizar determinadas a\u00e7\u00f5es que se tornaram condicionamentos, o desejo de fumar poder\u00e1 surgir e a reca\u00edda ocorrer.<\/p>\n\n\n\n<p>A manuten\u00e7\u00e3o de uma mudan\u00e7a pode exigir a constru\u00e7\u00e3o de um conjunto de habilidades e estrat\u00e9gias diferentes daquelas que foram inicialmente necess\u00e1rias para a obten\u00e7\u00e3o da mudan\u00e7a. <strong>Se a reca\u00edda ocorrer n\u00e3o deve ser encarada como fracasso<\/strong>. Comece tudo novamente e procure ficar mais atento ao que fez voc\u00ea voltar a fumar. D\u00ea-se v\u00e1rias chances at\u00e9 conseguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aumento-de-peso\"><span class=\"ez-toc-section\" id=\"Aumento_de_peso\"><\/span><strong>Aumento de peso<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A preocupa\u00e7\u00e3o com o ganho de peso \u00e9 uma das maiores barreiras para que alguns fumantes tomem a decis\u00e3o de parar de fumar, ou recaiam ap\u00f3s terem parado de fumar. <strong>\u00c9 importante entender que, geralmente, o ganho de peso ap\u00f3s a cessa\u00e7\u00e3o do tabagismo \u00e9 tempor\u00e1rio, sendo que na maioria dos casos, ocorre nos primeiros meses p\u00f3s-cessa\u00e7\u00e3o.<\/strong>Portanto, se a fome aumentar, n\u00e3o se assuste, \u00e9 normal um ganho de peso, pois seu paladar vai melhorando e o metabolismo se normalizando.<\/p>\n\n\n\n<p>De qualquer forma, procure n\u00e3o comer mais do que o de costume. Evite doces e alimentos gordurosos.<strong> Mantenha uma dieta equilibrada com alimentos naturais e de baixa caloria, frutas, verduras e legumes. Fa\u00e7a atividade f\u00edsica, pois ajuda no controle do peso<\/strong>. Beba sempre muito l\u00edquido, de prefer\u00eancia \u00e1gua e sucos naturais. No in\u00edcio, evite caf\u00e9 e bebidas alco\u00f3licas, pois eles estimulam a vontade de fumar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-beneficios\"><span class=\"ez-toc-section\" id=\"Beneficios\"><\/span><strong>Benef\u00edcios<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Parar de fumar sempre vale a pena em qualquer momento da vida, mesmo que o fumante j\u00e1 esteja com alguma doen\u00e7a causada pelo cigarro. Tais como c\u00e2ncer, enfisema ou derrame. A qualidade de vida melhora muito ao parar de fumar.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-veja-o-que-acontece-se-voce-parar-de-fumar-agora\"> Veja o que acontece se voc\u00ea parar de fumar agora:<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Ap\u00f3s 20 minutos, a press\u00e3o sangu\u00ednea e a pulsa\u00e7\u00e3o voltam ao normal.<\/strong><\/li><li><strong>Ap\u00f3s 2 horas, n\u00e3o h\u00e1 mais nicotina circulando no sangue.<\/strong><\/li><li><strong>Ap\u00f3s 8 horas, o n\u00edvel de oxig\u00eanio no sangue se normaliza.<\/strong><\/li><li><strong>Ap\u00f3s 12 a 24 horas, os pulm\u00f5es j\u00e1 funcionam melhor.<\/strong><\/li><li><strong>Ap\u00f3s 2 dias, o olfato j\u00e1 percebe melhor os cheiros e o paladar j\u00e1 degusta melhor a comida.<\/strong><\/li><li><strong>Ap\u00f3s 3 semanas, a respira\u00e7\u00e3o se torna mais f\u00e1cil e a circula\u00e7\u00e3o melhora.<\/strong><\/li><li><strong>Ap\u00f3s 1 ano, o risco de morte por infarto do mioc\u00e1rdio \u00e9 reduzido \u00e0 metade.<\/strong><\/li><li><strong>Ap\u00f3s 10 anos, o risco de sofrer infarto ser\u00e1 igual ao das pessoas que nunca fumaram.<\/strong><\/li><\/ul>\n\n\n\n<p><em><strong>Fonte: Programa Nacional de Controle do Tabagismo<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo.<\/p>\n","protected":false},"author":3,"featured_media":6799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2673,12],"tags":[81,115],"class_list":["post-5224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calendario-da-saude","category-temas-medicos","tag-especialidades-medicas","tag-pneumologia"],"acf":[],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v25.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dia Mundial Sem Tabaco destaca sa\u00fade pulmonar - Revisamed<\/title>\n<meta name=\"description\" content=\"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco\" \/>\n<meta property=\"og:description\" content=\"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\" \/>\n<meta property=\"og:site_name\" content=\"MedProvas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revisamedRM\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-31T15:01:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T18:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Revisamed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RevisamedRM\" \/>\n<meta name=\"twitter:site\" content=\"@RevisamedRM\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Revisamed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\"},\"author\":{\"name\":\"Revisamed\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/79121322845f0fd65eae5c73613d9cbe\"},\"headline\":\"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco\",\"datePublished\":\"2019-05-31T15:01:05+00:00\",\"dateModified\":\"2023-05-23T18:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\"},\"wordCount\":2774,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg\",\"keywords\":[\"especialidades m\u00e9dicas\",\"Pneumologia\"],\"articleSection\":[\"Calend\u00e1rio da Sa\u00fade\",\"Temas M\u00e9dicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\",\"url\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\",\"name\":\"Dia Mundial Sem Tabaco destaca sa\u00fade pulmonar - Revisamed\",\"isPartOf\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg\",\"datePublished\":\"2019-05-31T15:01:05+00:00\",\"dateModified\":\"2023-05-23T18:04:12+00:00\",\"description\":\"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo\",\"breadcrumb\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage\",\"url\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg\",\"contentUrl\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/medprovas.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#website\",\"url\":\"https:\/\/medprovas.com.br\/blog\/\",\"name\":\"MedProvas\",\"description\":\"O caminho mais f\u00e1cil para a sua Resid\u00eancia M\u00e9dica\",\"publisher\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/medprovas.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#organization\",\"name\":\"MedProvas\",\"url\":\"https:\/\/medprovas.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2024-12-09-at-16.01.57-1.jpeg\",\"contentUrl\":\"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2024-12-09-at-16.01.57-1.jpeg\",\"width\":1600,\"height\":348,\"caption\":\"MedProvas\"},\"image\":{\"@id\":\"https:\/\/medprovas.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revisamedRM\",\"https:\/\/x.com\/RevisamedRM\",\"https:\/\/www.instagram.com\/medprovas_revisamed?igsh=dnk0M2N4YnB5Z2Jo\",\"https:\/\/www.linkedin.com\/company\/revisamedrm\/mycompany\/\",\"https:\/\/m.youtube.com\/@medprovas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/79121322845f0fd65eae5c73613d9cbe\",\"name\":\"Revisamed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd011dda0cae554d6925a1acdeceacbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd011dda0cae554d6925a1acdeceacbe?s=96&d=mm&r=g\",\"caption\":\"Revisamed\"},\"url\":\"https:\/\/medprovas.com.br\/blog\/author\/claudia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dia Mundial Sem Tabaco destaca sa\u00fade pulmonar - Revisamed","description":"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/","og_locale":"pt_BR","og_type":"article","og_title":"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco","og_description":"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo","og_url":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/","og_site_name":"MedProvas","article_publisher":"https:\/\/www.facebook.com\/revisamedRM","article_published_time":"2019-05-31T15:01:05+00:00","article_modified_time":"2023-05-23T18:04:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg","type":"image\/jpeg"}],"author":"Revisamed","twitter_card":"summary_large_image","twitter_creator":"@RevisamedRM","twitter_site":"@RevisamedRM","twitter_misc":{"Escrito por":"Revisamed","Est. tempo de leitura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#article","isPartOf":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/"},"author":{"name":"Revisamed","@id":"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/79121322845f0fd65eae5c73613d9cbe"},"headline":"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco","datePublished":"2019-05-31T15:01:05+00:00","dateModified":"2023-05-23T18:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/"},"wordCount":2774,"commentCount":0,"publisher":{"@id":"https:\/\/medprovas.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage"},"thumbnailUrl":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg","keywords":["especialidades m\u00e9dicas","Pneumologia"],"articleSection":["Calend\u00e1rio da Sa\u00fade","Temas M\u00e9dicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/","url":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/","name":"Dia Mundial Sem Tabaco destaca sa\u00fade pulmonar - Revisamed","isPartOf":{"@id":"https:\/\/medprovas.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage"},"image":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage"},"thumbnailUrl":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg","datePublished":"2019-05-31T15:01:05+00:00","dateModified":"2023-05-23T18:04:12+00:00","description":"Dia Mundial sem tabaco, 31\/5, \u00e9 destinado \u00e0 conscientiza\u00e7\u00e3o sobre os impactos do cigarro na sa\u00fade.Cerca de 90% dos c\u00e2nceres de pulm\u00e3o s\u00e3o causados pelo fumo","breadcrumb":{"@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#primaryimage","url":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg","contentUrl":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2019\/05\/sem-tabaco1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/medprovas.com.br\/blog\/dia-mundial-sem-tabaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/medprovas.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"\u201cSa\u00fade pulmonar\u201d \u00e9 o tema do Dia Mundial Sem Tabaco"}]},{"@type":"WebSite","@id":"https:\/\/medprovas.com.br\/blog\/#website","url":"https:\/\/medprovas.com.br\/blog\/","name":"MedProvas","description":"O caminho mais f\u00e1cil para a sua Resid\u00eancia M\u00e9dica","publisher":{"@id":"https:\/\/medprovas.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medprovas.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/medprovas.com.br\/blog\/#organization","name":"MedProvas","url":"https:\/\/medprovas.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/medprovas.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2024-12-09-at-16.01.57-1.jpeg","contentUrl":"https:\/\/medprovas.com.br\/blog\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2024-12-09-at-16.01.57-1.jpeg","width":1600,"height":348,"caption":"MedProvas"},"image":{"@id":"https:\/\/medprovas.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revisamedRM","https:\/\/x.com\/RevisamedRM","https:\/\/www.instagram.com\/medprovas_revisamed?igsh=dnk0M2N4YnB5Z2Jo","https:\/\/www.linkedin.com\/company\/revisamedrm\/mycompany\/","https:\/\/m.youtube.com\/@medprovas"]},{"@type":"Person","@id":"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/79121322845f0fd65eae5c73613d9cbe","name":"Revisamed","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/medprovas.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd011dda0cae554d6925a1acdeceacbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd011dda0cae554d6925a1acdeceacbe?s=96&d=mm&r=g","caption":"Revisamed"},"url":"https:\/\/medprovas.com.br\/blog\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/posts\/5224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5224"}],"version-history":[{"count":12,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/posts\/5224\/revisions"}],"predecessor-version":[{"id":25648,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/posts\/5224\/revisions\/25648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/media\/6799"}],"wp:attachment":[{"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medprovas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}